{"id":7201,"date":"2020-01-25T11:09:56","date_gmt":"2020-01-25T10:09:56","guid":{"rendered":"https:\/\/www.litoral.es\/guia-de-vacaciones\/?p=7201"},"modified":"2020-03-12T12:57:57","modified_gmt":"2020-03-12T11:57:57","slug":"crucero-mediterraneo-descubrir-tarragona","status":"publish","type":"post","link":"https:\/\/www.litoral.es\/guia-de-vacaciones\/crucero-mediterraneo-descubrir-tarragona\/","title":{"rendered":"Crucero por el Mediterr\u00e1neo para descubrir Tarragona"},"content":{"rendered":"<p>Aprovechen los cruceros por el Mediterr\u00e1neo para descubrir la aut\u00e9ntica ciudad de Tarragona situada en Catalu\u00f1a, a unos cien kil\u00f3metros de Barcelona. Una peque\u00f1a distancia de m\u00e1s o menos 7 kil\u00f3metros separa el puerto de Tarragona del centro hist\u00f3rico de la ciudad.<\/p>\n<h2>Exploren los yacimientos romanos de Tarragona<\/h2>\n<p>La <a href=\"https:\/\/www.cruceros.es\/c-2-costa-cruceros\">compa\u00f1\u00eda Costa Cruceros con cruceros.es<\/a> \u00ables propone numerosos cruceros por el Mediterr\u00e1neo haciendo escala en Tarragona, ciudad espa\u00f1ola a menudo apodada \u00abPeque\u00f1a Barcelona\u00bb y clasificada como Patrimonio de la Humanidad por la UNESCO. Descubran los vestigios de la civilizaci\u00f3n romana conservados en esta ciudad catalana. En un yacimiento costero, admiren un anfiteatro romano donde tuvieron lugar luchas de gladiadores y de fieras, demostraciones de caza, etc. Este lugar alberg\u00f3 una bas\u00edlica visigoda en el siglo VI y una iglesia rom\u00e1nica en el siglo XII.<br \/>\n T\u00f3mense tambi\u00e9n el tiempo necesario para apreciar los vestigios del circo romano donde se desarrollaban las carreras de caballos y carros. Este circo de 30.000 plazas se situaba entre el Foro Provincial y la V\u00eda Augusta. En las cercan\u00edas descubran el Pretorio Romano donde se encuentran las escaleras que conducen a la parte subterr\u00e1nea de la ciudad. Esta impresionante torre fu\u00e9 en primer lugar el palacio de los reyes de la corona de Arag\u00f3n y luego una prisi\u00f3n. Para conocer m\u00e1s sobre el pasado antiguo de Tarragona, visiten el Museo Nacional Arqueol\u00f3gico de la ciudad.<\/p>\n<h2>Visiten al casco antiguo de la ciudad medieval de Tarragona<\/h2>\n<p>Durante una escala del crucero, recorran las calles empedradas del casco antiguo fortificado de Tarragona. Visiten lugares aut\u00e9nticos como la plaza del Rei y la calle Merceria con sus arcadas. Admiren hermosas casas medievales, algunas de las cuales con sorprendentes fachadas adornadas de antiguas inscripciones funerarias. La mayor\u00eda de estas casas fueron construidas en la Edad Media a partir de las ruinas romanas de la ciudad.<br \/>\n Pasen una hora visitando la catedral dedicada a Santa Tecla, la patrona de Tarragona. Es uno de los monumentos medievales m\u00e1s impresionantes de la ciudad. Este edificio religioso mezcla sutilmente los estilos arquitect\u00f3nicos rom\u00e1nico, g\u00f3tico y barroco. Su fachada de piedra pintada de blanco y amarillo data del siglo XII. En el interior, admiren el altar mayor monol\u00edtico, un retablo g\u00f3tico y un \u00f3rgano barroco.<\/p>\n<h2>Descubran la cara moderna de Tarragona<\/h2>\n<p>Durante la escala de su crucero d\u00e9n un paseo por la parte moderna de Tarragona. Recorran la Rambla Nova, la avenida principal rodeada de tiendas y restaurantes. Este es el lugar adecuado para sumergirse en el ambiente local. En medio de esta avenida, podr\u00e1n admirar los \u00abCastells\u00bb, torres humanas que muestran la cultura catalana. Situado a pocos pasos de la Rambla, el mercado central es otro lugar de la ciudad moderna que no hay que perderse. Este mercado ocupa un enorme edificio modernista que data de 1915.<br \/>\n Si el tiempo lo permite, prolonguen su excursi\u00f3n hasta el barrio de El Serrallo. Descubran este aut\u00e9ntico barrio de pescadores que se extiende junto al mar. Las pescas del d\u00eda se subastan todas las tardes. Es un espect\u00e1culo muy animado y ex\u00f3tico. Cerca de los puertos pesqueros y deportivos, encontrar\u00e1n buenos restaurantes para degustar deliciosos platos a base de pescados y mariscos reci\u00e9n pescados.<\/p>\n<h3>Disfruten de una gran variedad de actividades en Tarragona<\/h3>\n<p>Tarragona cuenta con unos quince kil\u00f3metros de costa bordeada de calas y de atractivas playas. Durante su escala de crucero, visiten las playas de arena fina de la Costa Dorada. Gracias al clima templado de la regi\u00f3n, estas playas son ideales para nadar entre junio y septiembre y para tomar el sol casi todo el a\u00f1o. Su larga franja de arena suave se presta para tomar el sol y para pasear junto al mar.<br \/>\n Para los adictos de emociones, esta parada de crucero en Tarragona es una oportunidad para visitar el parque tem\u00e1tico PortAventura World del Grupo Ferrari. Situado en Salou, a unos 20 minutos al suroeste del puerto de Tarragona, este complejo de 70.000 metros cuadrados ofrece una gran variedad de atracciones, incluyendo las monta\u00f1as rusas m\u00e1s r\u00e1pidas de Europa.<\/p>\n<p>Autor invitado: Cruceros.crucerosonline.com<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aprovechen los cruceros por el Mediterr\u00e1neo para descubrir la aut\u00e9ntica ciudad de Tarragona situada en Catalu\u00f1a, a unos cien kil\u00f3metros de Barcelona. Una peque\u00f1a distancia de m\u00e1s o menos 7 kil\u00f3metros separa el puerto de Tarragona del centro hist\u00f3rico de la ciudad. Exploren los yacimientos romanos de Tarragona La compa\u00f1\u00eda Costa Cruceros con cruceros.es \u00ables [&#8230;]<\/p>\n<p><a class=\"understrap-read-more-link btn btn-outline-dark btn-sm\" href=\"https:\/\/www.litoral.es\/guia-de-vacaciones\/crucero-mediterraneo-descubrir-tarragona\/\">Continue Reading&#8230;<\/a><\/p>\n","protected":false},"author":3,"featured_media":7202,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.2.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Crucero por el Mediterr\u00e1neo para descubrir Tarragona | Litoral Costa Dorada Blog<\/title>\n<meta name=\"description\" content=\"Crucero por el Mediterr\u00e1neo para descubrir Tarragona. Informaci\u00f3n de inter\u00e9s para su viaje o vacaciones a la Costa Dorada\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.litoral.es\/guia-de-vacaciones\/crucero-mediterraneo-descubrir-tarragona\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Crucero por el Mediterr\u00e1neo para descubrir Tarragona | Litoral Costa Dorada Blog\" \/>\n<meta property=\"og:description\" content=\"Crucero por el Mediterr\u00e1neo para descubrir Tarragona. Informaci\u00f3n de inter\u00e9s para su viaje o vacaciones a la Costa Dorada\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.litoral.es\/guia-de-vacaciones\/crucero-mediterraneo-descubrir-tarragona\/\" \/>\n<meta property=\"og:site_name\" content=\"Litoral Costa Dorada Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/pages\/Litoral-Costa-Dorada\/461561627270721\" \/>\n<meta property=\"article:published_time\" content=\"2020-01-25T10:09:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-03-12T11:57:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.litoral.es\/guia-de-vacaciones\/wp-content\/uploads\/2018\/07\/Vista-de-la-Playa-tarragona-ciudad.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Sonia Gonzalez\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sonia Gonzalez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.litoral.es\/guia-de-vacaciones\/crucero-mediterraneo-descubrir-tarragona\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.litoral.es\/guia-de-vacaciones\/crucero-mediterraneo-descubrir-tarragona\/\"},\"author\":{\"name\":\"Sonia Gonzalez\",\"@id\":\"https:\/\/www.litoral.es\/guia-de-vacaciones\/#\/schema\/person\/d0afa04756ae3fa5e7a2d6a91003cd38\"},\"headline\":\"Crucero por el Mediterr\u00e1neo para descubrir Tarragona\",\"datePublished\":\"2020-01-25T10:09:56+00:00\",\"dateModified\":\"2020-03-12T11:57:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.litoral.es\/guia-de-vacaciones\/crucero-mediterraneo-descubrir-tarragona\/\"},\"wordCount\":723,\"publisher\":{\"@id\":\"https:\/\/www.litoral.es\/guia-de-vacaciones\/#organization\"},\"articleSection\":[\"Sin categorizar\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.litoral.es\/guia-de-vacaciones\/crucero-mediterraneo-descubrir-tarragona\/\",\"url\":\"https:\/\/www.litoral.es\/guia-de-vacaciones\/crucero-mediterraneo-descubrir-tarragona\/\",\"name\":\"Crucero por el Mediterr\u00e1neo para descubrir Tarragona | Litoral Costa Dorada Blog\",\"isPartOf\":{\"@id\":\"https:\/\/www.litoral.es\/guia-de-vacaciones\/#website\"},\"datePublished\":\"2020-01-25T10:09:56+00:00\",\"dateModified\":\"2020-03-12T11:57:57+00:00\",\"description\":\"Crucero por el Mediterr\u00e1neo para descubrir Tarragona. Informaci\u00f3n de inter\u00e9s para su viaje o vacaciones a la Costa Dorada\",\"breadcrumb\":{\"@id\":\"https:\/\/www.litoral.es\/guia-de-vacaciones\/crucero-mediterraneo-descubrir-tarragona\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.litoral.es\/guia-de-vacaciones\/crucero-mediterraneo-descubrir-tarragona\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.litoral.es\/guia-de-vacaciones\/crucero-mediterraneo-descubrir-tarragona\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.litoral.es\/guia-de-vacaciones\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Crucero por el Mediterr\u00e1neo para descubrir Tarragona\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.litoral.es\/guia-de-vacaciones\/#website\",\"url\":\"https:\/\/www.litoral.es\/guia-de-vacaciones\/\",\"name\":\"Litoral Costa Dorada Blog\",\"description\":\"Alquiler y venta de alojamientos tur\u00edsticos en la Costa Dorada\",\"publisher\":{\"@id\":\"https:\/\/www.litoral.es\/guia-de-vacaciones\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.litoral.es\/guia-de-vacaciones\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.litoral.es\/guia-de-vacaciones\/#organization\",\"name\":\"Litoral Costa Dorada Blog\",\"url\":\"https:\/\/www.litoral.es\/guia-de-vacaciones\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.litoral.es\/guia-de-vacaciones\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.litoral.es\/guia-de-vacaciones\/wp-content\/uploads\/2023\/11\/litoral_blog.png\",\"contentUrl\":\"https:\/\/www.litoral.es\/guia-de-vacaciones\/wp-content\/uploads\/2023\/11\/litoral_blog.png\",\"width\":1254,\"height\":221,\"caption\":\"Litoral Costa Dorada Blog\"},\"image\":{\"@id\":\"https:\/\/www.litoral.es\/guia-de-vacaciones\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/pages\/Litoral-Costa-Dorada\/461561627270721\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.litoral.es\/guia-de-vacaciones\/#\/schema\/person\/d0afa04756ae3fa5e7a2d6a91003cd38\",\"name\":\"Sonia Gonzalez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.litoral.es\/guia-de-vacaciones\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/8783ab6255cf09e64ea7ac21e046fe55?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/8783ab6255cf09e64ea7ac21e046fe55?s=96&d=mm&r=g\",\"caption\":\"Sonia Gonzalez\"},\"description\":\"Mi nombre es Sonia Gonzalez, vivo en Cambrils y soy diplomada en turismo. Mis grandes pasiones son la lectura y los viajes alrededor del mundo, conociendo y aprendiendo de sus gentes, sus costumbres y tradiciones.\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Crucero por el Mediterr\u00e1neo para descubrir Tarragona | Litoral Costa Dorada Blog","description":"Crucero por el Mediterr\u00e1neo para descubrir Tarragona. Informaci\u00f3n de inter\u00e9s para su viaje o vacaciones a la Costa Dorada","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.litoral.es\/guia-de-vacaciones\/crucero-mediterraneo-descubrir-tarragona\/","og_locale":"es_ES","og_type":"article","og_title":"Crucero por el Mediterr\u00e1neo para descubrir Tarragona | Litoral Costa Dorada Blog","og_description":"Crucero por el Mediterr\u00e1neo para descubrir Tarragona. Informaci\u00f3n de inter\u00e9s para su viaje o vacaciones a la Costa Dorada","og_url":"https:\/\/www.litoral.es\/guia-de-vacaciones\/crucero-mediterraneo-descubrir-tarragona\/","og_site_name":"Litoral Costa Dorada Blog","article_publisher":"https:\/\/www.facebook.com\/pages\/Litoral-Costa-Dorada\/461561627270721","article_published_time":"2020-01-25T10:09:56+00:00","article_modified_time":"2020-03-12T11:57:57+00:00","og_image":[{"width":1920,"height":1440,"url":"https:\/\/www.litoral.es\/guia-de-vacaciones\/wp-content\/uploads\/2018\/07\/Vista-de-la-Playa-tarragona-ciudad.jpg","type":"image\/jpeg"}],"author":"Sonia Gonzalez","twitter_misc":{"Written by":"Sonia Gonzalez","Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.litoral.es\/guia-de-vacaciones\/crucero-mediterraneo-descubrir-tarragona\/#article","isPartOf":{"@id":"https:\/\/www.litoral.es\/guia-de-vacaciones\/crucero-mediterraneo-descubrir-tarragona\/"},"author":{"name":"Sonia Gonzalez","@id":"https:\/\/www.litoral.es\/guia-de-vacaciones\/#\/schema\/person\/d0afa04756ae3fa5e7a2d6a91003cd38"},"headline":"Crucero por el Mediterr\u00e1neo para descubrir Tarragona","datePublished":"2020-01-25T10:09:56+00:00","dateModified":"2020-03-12T11:57:57+00:00","mainEntityOfPage":{"@id":"https:\/\/www.litoral.es\/guia-de-vacaciones\/crucero-mediterraneo-descubrir-tarragona\/"},"wordCount":723,"publisher":{"@id":"https:\/\/www.litoral.es\/guia-de-vacaciones\/#organization"},"articleSection":["Sin categorizar"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.litoral.es\/guia-de-vacaciones\/crucero-mediterraneo-descubrir-tarragona\/","url":"https:\/\/www.litoral.es\/guia-de-vacaciones\/crucero-mediterraneo-descubrir-tarragona\/","name":"Crucero por el Mediterr\u00e1neo para descubrir Tarragona | Litoral Costa Dorada Blog","isPartOf":{"@id":"https:\/\/www.litoral.es\/guia-de-vacaciones\/#website"},"datePublished":"2020-01-25T10:09:56+00:00","dateModified":"2020-03-12T11:57:57+00:00","description":"Crucero por el Mediterr\u00e1neo para descubrir Tarragona. Informaci\u00f3n de inter\u00e9s para su viaje o vacaciones a la Costa Dorada","breadcrumb":{"@id":"https:\/\/www.litoral.es\/guia-de-vacaciones\/crucero-mediterraneo-descubrir-tarragona\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.litoral.es\/guia-de-vacaciones\/crucero-mediterraneo-descubrir-tarragona\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.litoral.es\/guia-de-vacaciones\/crucero-mediterraneo-descubrir-tarragona\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.litoral.es\/guia-de-vacaciones\/"},{"@type":"ListItem","position":2,"name":"Crucero por el Mediterr\u00e1neo para descubrir Tarragona"}]},{"@type":"WebSite","@id":"https:\/\/www.litoral.es\/guia-de-vacaciones\/#website","url":"https:\/\/www.litoral.es\/guia-de-vacaciones\/","name":"Litoral Costa Dorada Blog","description":"Alquiler y venta de alojamientos tur\u00edsticos en la Costa Dorada","publisher":{"@id":"https:\/\/www.litoral.es\/guia-de-vacaciones\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.litoral.es\/guia-de-vacaciones\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.litoral.es\/guia-de-vacaciones\/#organization","name":"Litoral Costa Dorada Blog","url":"https:\/\/www.litoral.es\/guia-de-vacaciones\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.litoral.es\/guia-de-vacaciones\/#\/schema\/logo\/image\/","url":"https:\/\/www.litoral.es\/guia-de-vacaciones\/wp-content\/uploads\/2023\/11\/litoral_blog.png","contentUrl":"https:\/\/www.litoral.es\/guia-de-vacaciones\/wp-content\/uploads\/2023\/11\/litoral_blog.png","width":1254,"height":221,"caption":"Litoral Costa Dorada Blog"},"image":{"@id":"https:\/\/www.litoral.es\/guia-de-vacaciones\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/pages\/Litoral-Costa-Dorada\/461561627270721"]},{"@type":"Person","@id":"https:\/\/www.litoral.es\/guia-de-vacaciones\/#\/schema\/person\/d0afa04756ae3fa5e7a2d6a91003cd38","name":"Sonia Gonzalez","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.litoral.es\/guia-de-vacaciones\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/8783ab6255cf09e64ea7ac21e046fe55?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8783ab6255cf09e64ea7ac21e046fe55?s=96&d=mm&r=g","caption":"Sonia Gonzalez"},"description":"Mi nombre es Sonia Gonzalez, vivo en Cambrils y soy diplomada en turismo. Mis grandes pasiones son la lectura y los viajes alrededor del mundo, conociendo y aprendiendo de sus gentes, sus costumbres y tradiciones."}]}},"_links":{"self":[{"href":"https:\/\/www.litoral.es\/guia-de-vacaciones\/wp-json\/wp\/v2\/posts\/7201"}],"collection":[{"href":"https:\/\/www.litoral.es\/guia-de-vacaciones\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.litoral.es\/guia-de-vacaciones\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.litoral.es\/guia-de-vacaciones\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.litoral.es\/guia-de-vacaciones\/wp-json\/wp\/v2\/comments?post=7201"}],"version-history":[{"count":6,"href":"https:\/\/www.litoral.es\/guia-de-vacaciones\/wp-json\/wp\/v2\/posts\/7201\/revisions"}],"predecessor-version":[{"id":7209,"href":"https:\/\/www.litoral.es\/guia-de-vacaciones\/wp-json\/wp\/v2\/posts\/7201\/revisions\/7209"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.litoral.es\/guia-de-vacaciones\/wp-json\/wp\/v2\/media\/7202"}],"wp:attachment":[{"href":"https:\/\/www.litoral.es\/guia-de-vacaciones\/wp-json\/wp\/v2\/media?parent=7201"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.litoral.es\/guia-de-vacaciones\/wp-json\/wp\/v2\/categories?post=7201"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.litoral.es\/guia-de-vacaciones\/wp-json\/wp\/v2\/tags?post=7201"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}